{"id":46877,"date":"2025-03-31T13:03:30","date_gmt":"2025-03-31T11:03:30","guid":{"rendered":"https:\/\/ymmo-ag.ch\/immobilien\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\/"},"modified":"2026-07-13T09:11:25","modified_gmt":"2026-07-13T07:11:25","slug":"1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum","status":"publish","type":"casawp_property","link":"https:\/\/ymmo-ag.ch\/en\/immobilien\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\/","title":{"rendered":"Helle, grossz\u00fcgige 1.5 Zimmer Wohnung mitten im Zentrum"},"content":{"rendered":"<p>Nach Vereinbarung vermieten wir an zentraler Lage in Breitenbach eine helle 1.5-Zimmerwohnung an der Passwangstrasse 7 im EG, direkt im Zentrum.<\/p>\n<p>Die Wohnung ist kompakt, gut durchdacht und verf\u00fcgt \u00fcber:<\/p>\n<p>&#8211; K\u00fcche mit Glaskeramik, Backofen und K\u00fchlschrank<br \/>&#8211; Badezimmer mit WC\/Lavabo und Badewanne<br \/>&#8211; Zimmer mit hellem Plattenboden und zwei Fenstern<br \/>&#8211; Wohnfl\u00e4che 41 m2<\/p>\n<p>Die Wohnung eignet sich besonders gut f\u00fcr Wochenaufenthalter, Singles sowie Studierende. Die Bushaltestelle ist in wenigen Gehminuten problemlos erreichbar.<\/p>\n<p>Die Wohnung hat keinen Balkon. Die Liegenschaft verf\u00fcgt \u00fcber einen Lift.<\/p>\n<p>1 AEH Parkplatz kann f\u00fcr CHF 100.- \/mtl. dazu gemietet werden.<\/p>\n<p>Gerne stehen wir Ihnen f\u00fcr einen unverbindlichen Besichtigungstermin zur Verf\u00fcgung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1.5 Zimmer Wohnung im Zentrum von Breitenbach<\/p>\n","protected":false},"author":0,"featured_media":46880,"parent":0,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"casawp_category":[137],"casawp_feature":[144],"casawp_utility":[125],"casawp_location":[171,128,170],"casawp_salestype":[169],"casawp_availability":[127],"casawp_region":[],"class_list":["post-46877","casawp_property","type-casawp_property","status-publish","has-post-thumbnail","hentry","casawp_category-apartment","casawp_feature-is-well-tended","casawp_utility-residential","casawp_location-locality_breitenbach","casawp_location-country_ch","casawp_location-region_so","casawp_salestype-rent","casawp_availability-active"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Helle, grossz\u00fcgige 1.5 Zimmer Wohnung mitten im Zentrum - YMMO AG | Architektur - Generalunternehmung - Immobilien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ymmo-ag.ch\/en\/immobilien\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Helle, grossz\u00fcgige 1.5 Zimmer Wohnung mitten im Zentrum - YMMO AG | Architektur - Generalunternehmung - Immobilien\" \/>\n<meta property=\"og:description\" content=\"1.5 Zimmer Wohnung im Zentrum von Breitenbach\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ymmo-ag.ch\/en\/immobilien\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\/\" \/>\n<meta property=\"og:site_name\" content=\"YMMO AG | Architektur - Generalunternehmung - Immobilien\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T07:11:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/immobilien\\\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\\\/\",\"url\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/immobilien\\\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\\\/\",\"name\":\"Helle, grossz\u00fcgige 1.5 Zimmer Wohnung mitten im Zentrum - YMMO AG | Architektur - Generalunternehmung - Immobilien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/immobilien\\\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/immobilien\\\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-13412\\\/property-1569879\\\/3d8a9f8ba7b06ac0f6113ca09761487e.png?p=xl\",\"datePublished\":\"2025-03-31T11:03:30+00:00\",\"dateModified\":\"2026-07-13T07:11:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/immobilien\\\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/immobilien\\\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/immobilien\\\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-13412\\\/property-1569879\\\/3d8a9f8ba7b06ac0f6113ca09761487e.png?p=xl\",\"contentUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-13412\\\/property-1569879\\\/3d8a9f8ba7b06ac0f6113ca09761487e.png?p=xl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/immobilien\\\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immobilien\",\"item\":\"https:\\\/\\\/ymmo-ag.ch\\\/immobilien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Helle, grossz\u00fcgige 1.5 Zimmer Wohnung mitten im Zentrum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/\",\"name\":\"YMMO AG | Architektur - Generalunternehmung - Immobilien\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/#organization\",\"name\":\"YMMO AG | Architektur - Generalunternehmung - Immobilien\",\"url\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ymmo-ag.ch\\\/wp-content\\\/uploads\\\/sites\\\/106\\\/2025\\\/04\\\/logo-ymmo-1.svg\",\"contentUrl\":\"https:\\\/\\\/ymmo-ag.ch\\\/wp-content\\\/uploads\\\/sites\\\/106\\\/2025\\\/04\\\/logo-ymmo-1.svg\",\"width\":958,\"height\":316,\"caption\":\"YMMO AG | Architektur - Generalunternehmung - Immobilien\"},\"image\":{\"@id\":\"https:\\\/\\\/ymmo-ag.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Helle, grossz\u00fcgige 1.5 Zimmer Wohnung mitten im Zentrum - YMMO AG | Architektur - Generalunternehmung - Immobilien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ymmo-ag.ch\/en\/immobilien\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\/","og_locale":"en_US","og_type":"article","og_title":"Helle, grossz\u00fcgige 1.5 Zimmer Wohnung mitten im Zentrum - YMMO AG | Architektur - Generalunternehmung - Immobilien","og_description":"1.5 Zimmer Wohnung im Zentrum von Breitenbach","og_url":"https:\/\/ymmo-ag.ch\/en\/immobilien\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\/","og_site_name":"YMMO AG | Architektur - Generalunternehmung - Immobilien","article_modified_time":"2026-07-13T07:11:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ymmo-ag.ch\/en\/immobilien\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\/","url":"https:\/\/ymmo-ag.ch\/en\/immobilien\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\/","name":"Helle, grossz\u00fcgige 1.5 Zimmer Wohnung mitten im Zentrum - YMMO AG | Architektur - Generalunternehmung - Immobilien","isPartOf":{"@id":"https:\/\/ymmo-ag.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ymmo-ag.ch\/en\/immobilien\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\/#primaryimage"},"image":{"@id":"https:\/\/ymmo-ag.ch\/en\/immobilien\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.casasoft.com\/media\/provider-13412\/property-1569879\/3d8a9f8ba7b06ac0f6113ca09761487e.png?p=xl","datePublished":"2025-03-31T11:03:30+00:00","dateModified":"2026-07-13T07:11:25+00:00","breadcrumb":{"@id":"https:\/\/ymmo-ag.ch\/en\/immobilien\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ymmo-ag.ch\/en\/immobilien\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ymmo-ag.ch\/en\/immobilien\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\/#primaryimage","url":"https:\/\/cdn.casasoft.com\/media\/provider-13412\/property-1569879\/3d8a9f8ba7b06ac0f6113ca09761487e.png?p=xl","contentUrl":"https:\/\/cdn.casasoft.com\/media\/provider-13412\/property-1569879\/3d8a9f8ba7b06ac0f6113ca09761487e.png?p=xl"},{"@type":"BreadcrumbList","@id":"https:\/\/ymmo-ag.ch\/en\/immobilien\/1569879en-helle-grosszuegige-15-zimmer-wohnung-mitten-im-zentrum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ymmo-ag.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Immobilien","item":"https:\/\/ymmo-ag.ch\/immobilien\/"},{"@type":"ListItem","position":3,"name":"Helle, grossz\u00fcgige 1.5 Zimmer Wohnung mitten im Zentrum"}]},{"@type":"WebSite","@id":"https:\/\/ymmo-ag.ch\/en\/#website","url":"https:\/\/ymmo-ag.ch\/en\/","name":"YMMO AG | Architektur - Generalunternehmung - Immobilien","description":"","publisher":{"@id":"https:\/\/ymmo-ag.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ymmo-ag.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ymmo-ag.ch\/en\/#organization","name":"YMMO AG | Architektur - Generalunternehmung - Immobilien","url":"https:\/\/ymmo-ag.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ymmo-ag.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ymmo-ag.ch\/wp-content\/uploads\/sites\/106\/2025\/04\/logo-ymmo-1.svg","contentUrl":"https:\/\/ymmo-ag.ch\/wp-content\/uploads\/sites\/106\/2025\/04\/logo-ymmo-1.svg","width":958,"height":316,"caption":"YMMO AG | Architektur - Generalunternehmung - Immobilien"},"image":{"@id":"https:\/\/ymmo-ag.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/casawp_property\/46877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/casawp_property"}],"about":[{"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/types\/casawp_property"}],"replies":[{"embeddable":true,"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/comments?post=46877"}],"version-history":[{"count":3,"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/casawp_property\/46877\/revisions"}],"predecessor-version":[{"id":46886,"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/casawp_property\/46877\/revisions\/46886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/media\/46880"}],"wp:attachment":[{"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/media?parent=46877"}],"wp:term":[{"taxonomy":"casawp_category","embeddable":true,"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/casawp_category?post=46877"},{"taxonomy":"casawp_feature","embeddable":true,"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/casawp_feature?post=46877"},{"taxonomy":"casawp_utility","embeddable":true,"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/casawp_utility?post=46877"},{"taxonomy":"casawp_location","embeddable":true,"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/casawp_location?post=46877"},{"taxonomy":"casawp_salestype","embeddable":true,"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/casawp_salestype?post=46877"},{"taxonomy":"casawp_availability","embeddable":true,"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/casawp_availability?post=46877"},{"taxonomy":"casawp_region","embeddable":true,"href":"https:\/\/ymmo-ag.ch\/en\/wp-json\/wp\/v2\/casawp_region?post=46877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}